{"id":276632,"date":"2024-05-09T05:40:27","date_gmt":"2024-05-09T05:40:27","guid":{"rendered":"https:\/\/pexlivanidis.com\/product\/pto-bearing-massey-ferguson-390-399-4200"},"modified":"2026-07-13T10:00:24","modified_gmt":"2026-07-13T07:00:24","slug":"makaronwto-pto-massey-ferguson-390-399-4200-2","status":"publish","type":"product","link":"https:\/\/pexlivanidis.com\/en\/product\/makaronwto-pto-massey-ferguson-390-399-4200-2\/","title":{"rendered":"PTO bearing Massey Ferguson 390-399-4200"},"content":{"rendered":"<p>12 gear speed bearing for the PTO Dimensions: 31.75\u00d741.28\u00d719.05mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>12 gear speed bearing for the PTO Dimensions: 31.75&#215;41.28&#215;19.05mm<\/p>\n","protected":false},"featured_media":509263,"template":"","meta":[],"product_brand":[],"product_cat":[2688],"product_tag":[],"class_list":{"0":"post-276632","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-transmission-en","7":"pa_landini-model-9550-en","8":"pa_manufacturer-massey-ferguson-en","9":"pa_massey-model-1000-en","10":"pa_massey-model-1004-en","11":"pa_massey-model-1004t-en","12":"pa_massey-model-158-en","13":"pa_massey-model-168-en","14":"pa_massey-model-243-en","15":"pa_massey-model-253-en","16":"pa_massey-model-260-en","17":"pa_massey-model-263-en","18":"pa_massey-model-265-en","19":"pa_massey-model-2680-en","20":"pa_massey-model-275-en","21":"pa_massey-model-290-en","22":"pa_massey-model-298-en","23":"pa_massey-model-340-en","24":"pa_massey-model-342-en","25":"pa_massey-model-350-en","26":"pa_massey-model-352-en","27":"pa_massey-model-355-en","28":"pa_massey-model-360-en","29":"pa_massey-model-362-en","30":"pa_massey-model-365-en","31":"pa_massey-model-372-en","32":"pa_massey-model-375-en","33":"pa_massey-model-382-en","34":"pa_massey-model-390-en","35":"pa_massey-model-390t-en","36":"pa_massey-model-396-en","37":"pa_massey-model-398-en","38":"pa_massey-model-399-en","39":"pa_massey-model-410-en","40":"pa_massey-model-420-en","41":"pa_massey-model-4215-en","42":"pa_massey-model-4220-en","43":"pa_massey-model-4225-en","44":"pa_massey-model-4235-en","45":"pa_massey-model-4240-en","46":"pa_massey-model-4245-en","47":"pa_massey-model-425-en","48":"pa_massey-model-4255-en","49":"pa_massey-model-4260-en","50":"pa_massey-model-4265-en","51":"pa_massey-model-4270-en","52":"pa_massey-model-430-en","53":"pa_massey-model-4315-en","54":"pa_massey-model-4320-en","55":"pa_massey-model-4325-en","56":"pa_massey-model-4335-en","57":"pa_massey-model-4345-en","58":"pa_massey-model-435-en","59":"pa_massey-model-4355-en","60":"pa_massey-model-4360-en","61":"pa_massey-model-4365-en","62":"pa_massey-model-4370-en","63":"pa_massey-model-440-en","64":"pa_massey-model-445-en","65":"pa_massey-model-450-en","66":"pa_massey-model-460-en","67":"pa_massey-model-461-en","68":"pa_massey-model-465-en","69":"pa_massey-model-475-en","70":"pa_massey-model-5285-en","71":"pa_massey-model-5290-en","72":"pa_massey-model-5335-en","73":"pa_massey-model-5340-en","74":"pa_massey-model-5355-en","75":"pa_massey-model-5360-en","76":"pa_massey-model-5365-en","77":"pa_massey-model-575-en","78":"pa_massey-model-590-en","79":"pa_massey-model-592-en","80":"pa_massey-model-595-en","81":"pa_massey-model-675-en","82":"pa_massey-model-690-en","83":"pa_massey-model-698-en","84":"pa_massey-model-698t-en","85":"pa_massey-model-699-en","86":"pa_substitute_codes-1677724-en","87":"pa_substitute_codes-1677724m1-en","88":"pa_substitute_codes-251-2-en","89":"pa_substitute_codes-bh2012-en","90":"pa_substitute_codes-m076-06600-en","91":"pa_substitute_codes-smf-11169-en","92":"pa_substitute_codes-smf-8725-en","93":"pa_substitute_codes-smf-8726-en","94":"pa_typos-gnisia-en","96":"first","97":"instock","98":"taxable","99":"shipping-taxable","100":"purchasable","101":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product\/276632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/media\/509263"}],"wp:attachment":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/media?parent=276632"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_brand?post=276632"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_cat?post=276632"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_tag?post=276632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}