{"id":284087,"date":"2024-05-09T16:44:15","date_gmt":"2024-05-09T16:44:15","guid":{"rendered":"https:\/\/pexlivanidis.com\/product\/pto-shaft-massey-ferguson-5400-6100-6200-6400"},"modified":"2026-05-19T17:04:19","modified_gmt":"2026-05-19T14:04:19","slug":"aksonas-pto-massey-ferguson-5400-6100-6200-6400-2","status":"publish","type":"product","link":"https:\/\/pexlivanidis.com\/en\/product\/aksonas-pto-massey-ferguson-5400-6100-6200-6400-2\/","title":{"rendered":"PTO shaft Massey Ferguson 5400-6100-6200-6400"},"content":{"rendered":"<p>Shaft for the PTO with 6 and 18 splines Length: 310mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shaft for the PTO with 6 and 18 splines Length: 310mm<\/p>\n","protected":false},"featured_media":592214,"template":"","meta":[],"product_brand":[],"product_cat":[2692],"product_tag":[],"class_list":{"0":"post-284087","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pto-drive-mechanism-en","7":"pa_manufacturer-massey-ferguson-en","8":"pa_massey-model-5425-en","9":"pa_massey-model-5435-en","10":"pa_massey-model-5435tier3-en","11":"pa_massey-model-5445-en","12":"pa_massey-model-5445tier3-en","13":"pa_massey-model-5455-en","14":"pa_massey-model-5455tier3-en","15":"pa_massey-model-5460-en","16":"pa_massey-model-5460tier3-en","17":"pa_massey-model-5465-en","18":"pa_massey-model-5465tier3-en","19":"pa_massey-model-5470-en","20":"pa_massey-model-5470tier3-en","21":"pa_massey-model-5475tier3-en","22":"pa_massey-model-5480tier3-en","23":"pa_massey-model-6120-en","24":"pa_massey-model-6130-en","25":"pa_massey-model-6140-en","26":"pa_massey-model-6150-en","27":"pa_massey-model-6160-en","28":"pa_massey-model-6170-en","29":"pa_massey-model-6180-en","30":"pa_massey-model-6190-en","31":"pa_massey-model-6235-en","32":"pa_massey-model-6245-en","33":"pa_massey-model-6255-en","34":"pa_massey-model-6260-en","35":"pa_massey-model-6265-en","36":"pa_massey-model-6270-en","37":"pa_massey-model-6280-en","38":"pa_massey-model-6290-en","39":"pa_massey-model-6445-en","40":"pa_massey-model-6445tier3-en","41":"pa_massey-model-6455-en","42":"pa_massey-model-6455tier3-en","43":"pa_massey-model-6460-en","44":"pa_massey-model-6460tier3-en","45":"pa_massey-model-6465-en","46":"pa_massey-model-6465tier3-en","47":"pa_massey-model-6470-en","48":"pa_massey-model-6470tier3-en","49":"pa_massey-model-6475-en","50":"pa_massey-model-6475tier3-en","51":"pa_massey-model-6480-en","52":"pa_massey-model-6480tier3-en","53":"pa_massey-model-6612-en","54":"pa_massey-model-6613-en","55":"pa_massey-model-6614-en","56":"pa_massey-model-6615-en","57":"pa_massey-model-6616-en","58":"pa_massey-model-6712-en","59":"pa_massey-model-6713-en","60":"pa_massey-model-6714-en","61":"pa_massey-model-6715-en","62":"pa_massey-model-6716-en","63":"pa_massey-model-6718-en","64":"pa_massey-model-7614-en","65":"pa_massey-model-7615-en","66":"pa_massey-model-7616-en","67":"pa_massey-model-7618-en","68":"pa_massey-model-7714-en","69":"pa_massey-model-7715-en","70":"pa_massey-model-7716-en","71":"pa_massey-model-7718-en","72":"pa_substitute_codes-260157-en","73":"pa_substitute_codes-3712033-en","74":"pa_substitute_codes-3712033m2-en","75":"pa_substitute_codes-64532-en","76":"pa_substitute_codes-64575-en","77":"pa_substitute_codes-k13058-en","78":"pa_typos-aftermarket-en","80":"first","81":"outofstock","82":"taxable","83":"shipping-taxable","84":"purchasable","85":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product\/284087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/media\/592214"}],"wp:attachment":[{"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/media?parent=284087"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_brand?post=284087"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_cat?post=284087"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pexlivanidis.com\/en\/wp-json\/wp\/v2\/product_tag?post=284087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}